{"id":409,"count":45,"description":"","link":"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services","name":"Products and Services","slug":"products-and-services","taxonomy":"category","parent":0,"meta":[],"acf":[],"z_taxonomy_image_url":"https:\/\/www.legroupeforget.com\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Products and Services Archives - Le Groupe Forget<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Products and Services Archives - Le Groupe Forget\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services\" \/>\n<meta property=\"og:site_name\" content=\"Le Groupe Forget\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.legroupeforget.com\/wp-content\/uploads\/2018\/03\/logo_fr2x.png\" \/>\n\t<meta property=\"og:image:width\" content=\"262\" \/>\n\t<meta property=\"og:image:height\" content=\"110\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/en\\\/category\\\/products-and-services\",\"url\":\"https:\\\/\\\/www.legroupeforget.com\\\/en\\\/category\\\/products-and-services\",\"name\":\"Products and Services Archives - Le Groupe Forget\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/en\\\/category\\\/products-and-services#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/en\\\/category\\\/products-and-services#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.legroupeforget.com\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products and Services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/#website\",\"url\":\"https:\\\/\\\/www.legroupeforget.com\\\/\",\"name\":\"Le Groupe Forget\",\"description\":\"Le Groupe Forget\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.legroupeforget.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/#organization\",\"name\":\"Le Groupe Forget\",\"url\":\"https:\\\/\\\/www.legroupeforget.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.legroupeforget.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_fr2x.png\",\"contentUrl\":\"https:\\\/\\\/www.legroupeforget.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_fr2x.png\",\"width\":262,\"height\":110,\"caption\":\"Le Groupe Forget\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legroupeforget.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cliniquesgroupeforget\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/groupe-forget\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Lauditionenbref\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Products and Services Archives - Le Groupe Forget","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services","og_locale":"en_US","og_type":"article","og_title":"Products and Services Archives - Le Groupe Forget","og_url":"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services","og_site_name":"Le Groupe Forget","og_image":[{"width":262,"height":110,"url":"https:\/\/www.legroupeforget.com\/wp-content\/uploads\/2018\/03\/logo_fr2x.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services","url":"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services","name":"Products and Services Archives - Le Groupe Forget","isPartOf":{"@id":"https:\/\/www.legroupeforget.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.legroupeforget.com\/en\/category\/products-and-services#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.legroupeforget.com\/en"},{"@type":"ListItem","position":2,"name":"Products and Services"}]},{"@type":"WebSite","@id":"https:\/\/www.legroupeforget.com\/#website","url":"https:\/\/www.legroupeforget.com\/","name":"Le Groupe Forget","description":"Le Groupe Forget","publisher":{"@id":"https:\/\/www.legroupeforget.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legroupeforget.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.legroupeforget.com\/#organization","name":"Le Groupe Forget","url":"https:\/\/www.legroupeforget.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.legroupeforget.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.legroupeforget.com\/wp-content\/uploads\/2018\/03\/logo_fr2x.png","contentUrl":"https:\/\/www.legroupeforget.com\/wp-content\/uploads\/2018\/03\/logo_fr2x.png","width":262,"height":110,"caption":"Le Groupe Forget"},"image":{"@id":"https:\/\/www.legroupeforget.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cliniquesgroupeforget","https:\/\/www.linkedin.com\/company\/groupe-forget\/","https:\/\/www.youtube.com\/c\/Lauditionenbref"]}]}},"_links":{"self":[{"href":"https:\/\/www.legroupeforget.com\/en\/wp-json\/wp\/v2\/categories\/409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legroupeforget.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.legroupeforget.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.legroupeforget.com\/en\/wp-json\/wp\/v2\/posts?categories=409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}